{"id":2778,"date":"2024-11-14T13:27:43","date_gmt":"2024-11-14T12:27:43","guid":{"rendered":"https:\/\/www.zahel.at\/produkt\/ried-kroissberg-wiener-gemischter-satz-dac-demeter-2021\/"},"modified":"2025-08-29T18:07:52","modified_gmt":"2025-08-29T16:07:52","slug":"ried-kroissberg-wiener-gemischter-satz-dac-demeter-2021","status":"publish","type":"product","link":"https:\/\/www.zahel.at\/en\/produkt\/ried-kroissberg-wiener-gemischter-satz-dac-demeter-2021\/","title":{"rendered":"Ried Kroissberg Wiener Gemischter Satz DAC Demeter 2021"},"content":{"rendered":"<p>This elegant Viennese Gemischter Satz comes from a south-facing slope on Vienna&#8217;s second highest hill, the Kroissberg. The 13 grape varieties are rooted in soils of Dolomite limestone and flysch sandstone, giving the wine an elegant expression.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>This elegant Wiener Gemischter Satz comes from a south-facing slope on Vienna&#8217;s second highest hill, the Kroissberg. The 13 grape varieties are rooted in soils of Dolomite limestone and flysch sandstone, giving the wine an elegant expression. The Wiener Gemischter Satz from the Kroissberg vineyard in our large vineyard on the Maurerberg is a white wine with an elegant and slightly spicy finish.<\/p>\n","protected":false},"featured_media":1285,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[82,74],"product_tag":[],"class_list":["post-2778","product","type-product","status-publish","has-post-thumbnail","product_cat-white-wine","product_cat-wine-sparkling-wine","pa_flaschengroesse-075l-en","pa_geschmack-dry-en","pa_jahrgang-2021-en","pa_lage-kroissberg-en","pa_sorte-chardonnay-en","pa_sorte-furmint-en","pa_sorte-gemischter-satz-en","pa_sorte-gruener-silvaner-en","pa_sorte-gruener-veltliner-en","pa_sorte-neuburg","pa_sorte-pinot-blanc-en-2","pa_sorte-pinot-gris-en","pa_sorte-red-traminer","pa_sorte-riesling-en","pa_sorte-rotgipfler-en","pa_sorte-yellow-traminer","pa_sorte-zierfandler-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.zahel.at\/en\/wp-json\/wp\/v2\/product\/2778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zahel.at\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.zahel.at\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zahel.at\/en\/wp-json\/wp\/v2\/media\/1285"}],"wp:attachment":[{"href":"https:\/\/www.zahel.at\/en\/wp-json\/wp\/v2\/media?parent=2778"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.zahel.at\/en\/wp-json\/wp\/v2\/product_brand?post=2778"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.zahel.at\/en\/wp-json\/wp\/v2\/product_cat?post=2778"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.zahel.at\/en\/wp-json\/wp\/v2\/product_tag?post=2778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}